{"id":2,"count":20,"description":"","link":"https:\/\/www.allied-telesis.co.jp\/netrend\/medical\/","name":"\u533b\u7642\u30fb\u75c5\u9662","slug":"medical","taxonomy":"category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.allied-telesis.co.jp\/netrend\/wp-json\/wp\/v2\/categories\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.allied-telesis.co.jp\/netrend\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.allied-telesis.co.jp\/netrend\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.allied-telesis.co.jp\/netrend\/wp-json\/wp\/v2\/posts?categories=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}